{"id":5313,"date":"2026-03-26T16:43:13","date_gmt":"2026-03-26T15:43:13","guid":{"rendered":"https:\/\/netprove.nl\/?page_id=5313"},"modified":"2026-03-26T17:14:46","modified_gmt":"2026-03-26T16:14:46","slug":"tools","status":"publish","type":"page","link":"https:\/\/netprove.nl\/en\/tools\/","title":{"rendered":"Tools"},"content":{"rendered":"<section class=\"wp-block alignfull item-slider\" id=\"item-slider-block_f209f8233f9c0e9f6e7b7ee730ec0ec0\">\n        <div class=\"row align-center\">\n            <div class=\"column small-12 large-4 text-center\">\n                <div class=\"section-title\">\n                                                        <\/div>\n            <\/div>\n        <\/div>\n        <div class=\"row items-section small-up-1 medium-up-2 large-up-3 flex-grow\">\n                            <div class=\"column\">\n                    <a href=\"https:\/\/netprove.nl\/en\/tools\/employee-net-promoter-score-calculation\/\" class=\"card card--event card--white grow\">\n                        <div class=\"card__image-wrapper\">\n                            <img decoding=\"async\" loading=\"lazy\" class=\"card__image aspect-ratio-12-8\" src=\"https:\/\/netprove.nl\/wp-content\/uploads\/2026\/03\/eNPS-calculator-e1774541424794-600x400.png\" alt=\"\" \/>\n                        <\/div>\n                        <div class=\"card__content grow\">\n                            <h3 class=\"card__title\">eNPS calculator<\/h3>\n                            <div class=\"card__text text-grow\">\n                                <p>Curious about your organisation's eNPS (employee Net Promoter Score)? Use our simple calculation tool to instantly calculate your score and get quick insight into the loyalty and satisfaction of...<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/a>\n                <\/div>\n                            <div class=\"column\">\n                    <a href=\"https:\/\/netprove.nl\/en\/tools\/enps-impact-calculator\/\" class=\"card card--event card--white grow\">\n                        <div class=\"card__image-wrapper\">\n                            <img decoding=\"async\" loading=\"lazy\" class=\"card__image aspect-ratio-12-8\" src=\"https:\/\/netprove.nl\/wp-content\/uploads\/2025\/12\/eNPS-calculator-600x400.png\" alt=\"\" \/>\n                        <\/div>\n                        <div class=\"card__content grow\">\n                            <h3 class=\"card__title\">eNPS impact calculator<\/h3>\n                            <div class=\"card__text text-grow\">\n                                <p>Why is eNPS (employee Net Promoter Score) important not only for employee well-being but also the financial health of employers? Calculate it with the eNPS calculator.<\/p>\n                            <\/div>\n                        <\/div>\n                    <\/a>\n                <\/div>\n                    <\/div>\n    <\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-5313","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/pages\/5313","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/comments?post=5313"}],"version-history":[{"count":8,"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/pages\/5313\/revisions"}],"predecessor-version":[{"id":5326,"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/pages\/5313\/revisions\/5326"}],"wp:attachment":[{"href":"https:\/\/netprove.nl\/en\/wp-json\/wp\/v2\/media?parent=5313"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}